{"id":1072,"date":"2013-06-26T10:17:28","date_gmt":"2013-06-26T10:17:28","guid":{"rendered":"http:\/\/kasperskydaily.com\/spain\/?p=1072"},"modified":"2020-02-26T17:15:39","modified_gmt":"2020-02-26T15:15:39","slug":"consejo-semanal-como-proteger-la-configuracion-de-tu-producto-antivirus","status":"publish","type":"post","link":"https:\/\/www.kaspersky.es\/blog\/consejo-semanal-como-proteger-la-configuracion-de-tu-producto-antivirus\/1072\/","title":{"rendered":"Consejo semanal: \u00bfC\u00f3mo proteger la configuraci\u00f3n de tu antivirus?"},"content":{"rendered":"<p>Imagina la siguiente situaci\u00f3n: has configurado la m\u00e1xima protecci\u00f3n para Kaspersky PURE; personalizado los ajustes de cada componente; elegido los datos de los que se har\u00e1, regularmente, una copia de seguridad y configurado el control remoto en tu port\u00e1til. Ahora, el \u00fanico asunto que te preocupa es que tu hijo utilice tu equipo inform\u00e1tico.<\/p>\n<p><a href=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2013\/06\/05230957\/04.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1075\" alt=\"Ajustes de PURE 3.0\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2013\/06\/05230957\/04.gif\" width=\"640\" height=\"480\"><\/a><\/p>\n<p>Como cualquier padre, prefieres excederte en la protecci\u00f3n porque necesitas asegurarte de que tu hijo no desactivar\u00e1 el producto o cambiar\u00e1 los ajustes disminuyendo el nivel de <a title=\"seguridad\" href=\"https:\/\/www.kaspersky.com\/sp\" target=\"_blank\" rel=\"noopener nofollow\">seguridad<\/a> del ordenador y perdiendo toda la informaci\u00f3n almacenada en el equipo.<\/p>\n<p>Para evitar cualquier desastre de este tipo, te recomendamos que restrinjas el acceso al producto <a title=\"Kaspersky PURE 3.0\" href=\"https:\/\/www.kaspersky.com\/sp\/pure\" target=\"_blank\" rel=\"noopener nofollow\">Kaspersky PURE 3.0<\/a> mediante una contrase\u00f1a. En la parte superior de la ventana \u201cConfiguraci\u00f3n\u201d, selecciona la pesta\u00f1a \u201cContrase\u00f1a\u201d y habilita la casilla \u201cActivar la protecci\u00f3n con contrase\u00f1a\u201d. Despu\u00e9s, solo tendr\u00e1s que introducir tu clave.<\/p>\n<p><a href=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2013\/06\/05230955\/contrasena_pure.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1076\" alt=\"Ajustes de PURE 3.0\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2013\/06\/05230955\/contrasena_pure.png\" width=\"717\" height=\"550\"><\/a><\/p>\n<p>En la secci\u00f3n inferior de la misma ventana, elige las funciones que quieres proteger con la contrase\u00f1a:<\/p>\n<ul>\n<li>Configurar la aplicaci\u00f3n<\/li>\n<li>Administraci\u00f3n de Copia de Seguridad<\/li>\n<li>Control de red dom\u00e9stica<\/li>\n<li>Administraci\u00f3n de Control Parental<\/li>\n<li>Salir de la aplicaci\u00f3n<\/li>\n<\/ul>\n<p>Atenci\u00f3n: si olvidas tu clave de protecci\u00f3n de Kaspersky PURE, sigue los pasos que se detallan en <a href=\"http:\/\/support.kaspersky.com\/9631\" target=\"_blank\" rel=\"noopener\">esta p\u00e1gina<\/a> (ingl\u00e9s).<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imagina la siguiente situaci\u00f3n: has configurado la m\u00e1xima protecci\u00f3n para Kaspersky PURE; personalizado los ajustes de cada componente; elegido los datos de los que se har\u00e1, regularmente, una copia de<\/p>\n","protected":false},"author":196,"featured_media":1074,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[123,340],"class_list":["post-1072","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tips","tag-contrasenas","tag-kaspersky-pure-3-0"],"hreflang":[{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/consejo-semanal-como-proteger-la-configuracion-de-tu-producto-antivirus\/1072\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.es\/blog\/tag\/contrasenas\/","name":"contrase\u00f1as"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts\/1072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/users\/196"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/comments?post=1072"}],"version-history":[{"count":2,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts\/1072\/revisions"}],"predecessor-version":[{"id":21357,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts\/1072\/revisions\/21357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/media\/1074"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/media?parent=1072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/categories?post=1072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/tags?post=1072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}