{"id":17989,"date":"2019-03-11T15:29:32","date_gmt":"2019-03-11T13:29:32","guid":{"rendered":"https:\/\/www.kaspersky.es\/blog\/?p=17989"},"modified":"2019-11-22T10:55:47","modified_gmt":"2019-11-22T08:55:47","slug":"mwc19-recap","status":"publish","type":"post","link":"https:\/\/www.kaspersky.es\/blog\/mwc19-recap\/17989\/","title":{"rendered":"Mobile World Congress 2019: Inteligencia Artificial y 5G"},"content":{"rendered":"<p>Lo que sucede en el <strong>Mobile World Congress<\/strong> siempre transciende. Las presentaciones que tienen lugar en uno de los eventos m\u00e1s importantes para las industrias de las telecomunicaciones y la electr\u00f3nica de consumo afectan a las vidas de casi todos. As\u00ed que, aunque no est\u00e9s interesado en <em>smartphones<\/em> o equipos de telecomunicaciones, vale la pena echar un vistazo a las <strong>novedades del MWC<\/strong>. \u00bfQu\u00e9 ha pasado en la conferencia de este a\u00f1o?<\/p>\n<h2>El 5G ya ha llegado<\/h2>\n<p>En primer lugar, el <strong>5G<\/strong> ya est\u00e1 aqu\u00ed. En los \u00faltimos a\u00f1os, hemos escuchado hablar del 5G, pero parece que el 2019 va a ser el a\u00f1o en el que la pr\u00f3xima generaci\u00f3n de redes se lance a todo el mundo.<\/p>\n<p>En el MWC19, tanto Qualcomm como Intel (l\u00edderes del mercado de chips) dedicaron su <em>stand<\/em> al 5G y todos los fabricantes m\u00e1s importantes de <em>smartphones<\/em> presentaron sus tel\u00e9fonos con esta tecnolog\u00eda. Por tanto, lo m\u00e1s probable es que tu pr\u00f3ximo <em>smartphone<\/em> admita 5G y utilices su red.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17991 size-full\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2019\/03\/11145637\/mwc19-recap-5g.jpg\" alt=\"Mobile World Congrees 2019: el 5G ya est\u00e1 aqu\u00ed\" width=\"1460\" height=\"950\"><\/p>\n<p>Como ya comentamos en esta publicaci\u00f3n sobre <a href=\"https:\/\/www.kaspersky.es\/blog\/why-we-need-5g-mobile-networks\/6122\/\" target=\"_blank\" rel=\"noopener\">por qu\u00e9 es necesario el 5G<\/a>, la principal <strong>ventaja del 5G<\/strong> no es la velocidad de la conexi\u00f3n de datos. S\u00ed, la velocidad mejorar\u00e1, pero la principal caracter\u00edstica del desarrollo del 5G es la capacidad de la red. Ya contamos unos mil millones de dispositivos conectados y, con la tendencia de los dispositivos inteligentes, el n\u00famero no deja de crecer. Esto nos introduce en el Internet de las Cosas, cuyos <a href=\"https:\/\/www.kaspersky.es\/blog\/securing-prosthetic-arm\/17936\/\" target=\"_blank\" rel=\"noopener\">problemas de seguridad<\/a> se volvieron a demostrar en el MWC19.<\/p>\n<h2>Lectores de huellas ultras\u00f3nicos<\/h2>\n<p>Qualcomm revel\u00f3 los <strong>lectores de huellas ultras\u00f3nicos<\/strong> hace 4 a\u00f1os, en el <a href=\"https:\/\/www.kaspersky.es\/blog\/mwc-2015-tendencias\/5543\/\" target=\"_blank\" rel=\"noopener\">Mobile World Congress del 2015<\/a>. Por aquel entonces, la tecnolog\u00eda era un mero prototipo, pero este a\u00f1o finalmente se ha implementado en productos reales, de hecho, muchos de los <em>smartphones<\/em> que se mostraron en el MWC2019 ya contaban con esta tecnolog\u00eda. En realidad, varios de ellos se presentaron meses antes del evento, pero parece que pronto aparecer\u00e1n muchos m\u00e1s.<\/p>\n<p>En comparaci\u00f3n con los lectores de huellas tradicionales, los ultras\u00f3nicos ofrecen varias ventajas. En primer lugar, no necesitan contacto, por tanto, pueden ocultarse bajo la pantalla del <em>smartphone<\/em>. Cuando el usuario tenga que proporcionar su huella digital, la pantalla mostrar\u00e1 d\u00f3nde tiene que colocar el dedo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17992 size-full\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2019\/03\/11145817\/mwc19-recap-ultrasonic-fingerprint.jpg\" alt=\"Muchos de los smartphones presentados en el MWC19 contaban con lectores de huellas ultras\u00f3nicos\" width=\"1460\" height=\"1080\"><\/p>\n<p>En segundo lugar, son m\u00e1s seguros. Los lectores ultras\u00f3nicos leen las <strong>huellas digitales en 3D<\/strong>, por lo que pueden detectar una huella impresa. Adem\u00e1s, son tan r\u00e1pidos que leen huellas digitales en tiempo real. Gracias a eso, pueden distinguir un dedo de una impresi\u00f3n en 3D o, incluso, de un dedo amputado o muerto. As\u00ed que se acab\u00f3 el t\u00edpico \u201c\u00bfy si alguien te corta el dedo y lo utiliza para desbloquear tu tel\u00e9fono?\u201d.<\/p>\n<p><strong>Inteligencia artificial<\/strong><\/p>\n<p>Sin duda, el tema de este Mobile World Congress fue la \u201c<strong>inteligencia artificial<\/strong>\u201c, de hecho, se dej\u00f3 ver hasta en el <em>stand<\/em> de Oral-B que exhib\u00eda su nuevo cepillo de dientes: \u201cGenius X con inteligencia artificial\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17993 size-full\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2019\/03\/11150039\/mwc19-recap-oral-b.jpg\" alt=\"Oral-B present\u00f3 su Genius X con Inteligencia artificial en el Mobile World Congress\" width=\"1460\" height=\"1000\"><\/p>\n<p>Esto quiere decir, a parte de la tendencia, que muchas empresas de todo el mundo se est\u00e1n inspirando en Amazon, Google y otros gigantes que trabajan con datos y se est\u00e1n tomando muy en serio la idea de aprovechar todo el valor posible de la enorme cantidad de datos que recopilan a diario. Y, por ello, utilizan inteligencia artificial o, en concreto, el aprendizaje autom\u00e1tico, la tecnolog\u00eda de la que todo el mundo habla cuando se menciona la <strong>IA<\/strong>.<\/p>\n<p>Resulta que el aprendizaje autom\u00e1tico es particularmente \u00fatil para combatir el <strong><em>malware<\/em><\/strong>. Por ello, Kaspersky Lab adapt\u00f3 pronto esta tecnolog\u00eda para proteger la <strong>seguridad online<\/strong> y ya contamos con una gran experiencia en este campo. Cabe recordar que, al igual que cualquier otra tecnolog\u00eda, la IA presenta ventajas e inconvenientes.<\/p>\n<p>Lo que diferencia a la IA del resto de tecnolog\u00edas es que puede presentar situaciones muy problem\u00e1ticas para la <a href=\"https:\/\/www.kaspersky.es\/blog\/machine-learning-nine-challenges\/16771\/\" target=\"_blank\" rel=\"noopener\">seguridad de los usuarios<\/a>. Adem\u00e1s, la producci\u00f3n de un sistema basado en IA puede ser inexplicable no solo para sus usuarios, sino tambi\u00e9n para los propios arquitectos. Dicho esto, es importante tener en cuenta estas <strong>desventajas de la IA<\/strong> y ser precavido durante su aplicaci\u00f3n en las tecnolog\u00edas que lo permitan, su elecci\u00f3n podr\u00eda tener un impacto importante en la sociedad y en nuestras vidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recordamos el Mobile World Congress 2019: 5G, Internet de las cosas, lectores de huellas ultras\u00f3nicos e inteligencia artificial<\/p>\n","protected":false},"author":40,"featured_media":17990,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2202,2754,6],"tags":[1268,456,2870,1307,1976,255,2860,2861],"class_list":{"0":"post-17989","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-business","8":"category-enterprise","9":"category-news","10":"tag-5g","11":"tag-biometrica","12":"tag-escaner-de-huella-digital","13":"tag-ia","14":"tag-idc","15":"tag-mobile-world-congress","16":"tag-mwc","17":"tag-mwc19"},"hreflang":[{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/mwc19-recap\/17989\/"},{"hreflang":"en-in","url":"https:\/\/www.kaspersky.co.in\/blog\/mwc19-recap\/15363\/"},{"hreflang":"en-ae","url":"https:\/\/me-en.kaspersky.com\/blog\/mwc19-recap\/12932\/"},{"hreflang":"en-us","url":"https:\/\/usa.kaspersky.com\/blog\/mwc19-recap\/17304\/"},{"hreflang":"en-gb","url":"https:\/\/www.kaspersky.co.uk\/blog\/mwc19-recap\/15459\/"},{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/mwc19-recap\/14157\/"},{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/mwc19-recap\/16999\/"},{"hreflang":"ru","url":"https:\/\/www.kaspersky.ru\/blog\/mwc19-recap\/22368\/"},{"hreflang":"tr","url":"https:\/\/www.kaspersky.com.tr\/blog\/mwc19-recap\/5748\/"},{"hreflang":"x-default","url":"https:\/\/www.kaspersky.com\/blog\/mwc19-recap\/25885\/"},{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/mwc19-recap\/11490\/"},{"hreflang":"pl","url":"https:\/\/plblog.kaspersky.com\/mwc19-recap\/10438\/"},{"hreflang":"de","url":"https:\/\/www.kaspersky.de\/blog\/mwc19-recap\/18684\/"},{"hreflang":"ja","url":"https:\/\/blog.kaspersky.co.jp\/mwc19-recap\/22740\/"},{"hreflang":"ru-kz","url":"https:\/\/blog.kaspersky.kz\/mwc19-recap\/18054\/"},{"hreflang":"en-au","url":"https:\/\/www.kaspersky.com.au\/blog\/mwc19-recap\/22236\/"},{"hreflang":"en-za","url":"https:\/\/www.kaspersky.co.za\/blog\/mwc19-recap\/22170\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.es\/blog\/tag\/mwc19\/","name":"MWC19"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts\/17989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/comments?post=17989"}],"version-history":[{"count":6,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts\/17989\/revisions"}],"predecessor-version":[{"id":19847,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts\/17989\/revisions\/19847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/media\/17990"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/media?parent=17989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/categories?post=17989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/tags?post=17989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}