{"id":5085,"date":"2014-12-19T19:31:17","date_gmt":"2014-12-19T19:31:17","guid":{"rendered":"http:\/\/kasperskydaily.com\/spain\/?p=5085"},"modified":"2020-02-26T17:27:14","modified_gmt":"2020-02-26T15:27:14","slug":"corea-del-norte-ataque-a-sony","status":"publish","type":"post","link":"https:\/\/www.kaspersky.es\/blog\/corea-del-norte-ataque-a-sony\/5085\/","title":{"rendered":"\u00bfEst\u00e1 Corea del Norte realmente detr\u00e1s del ataque a Sony?"},"content":{"rendered":"<p>Definitivamente el ataques de Sony parece ser el regalo que nos sigue dando esta \u00e9poca navide\u00f1a. Y si lo que normalmente se dice es verdad, toda esta pesadilla deriva de lo que promet\u00eda ser una comedia pueril llamada \u201cThe Interview\u201d (La Entrevista en ingl\u00e9s). El argumento de la pel\u00edcula gira en torno a un par de periodistas a quienes les conceden una entrevista con el l\u00edder supremo de Corea del Norte, Kim Jon-Un, y el consiguiente complot para asesinar posteriormente al Dictador tirano.<\/p>\n<p>Sony, que de nuevo fracasa a la hora de aprender la lecci\u00f3n despu\u00e9s de que <a href=\"https:\/\/threatpost.com\/sony-fined-250000-uk-over-failures-playstation-network-breach-012413\/77446\" target=\"_blank\" rel=\"noopener nofollow\">los atacantes hackearan la red de la Play Station dej\u00e1ndola en coma durante un mes en la primavera 2011<\/a>, es ahora el protagonista de otro incidente de seguridad grave y humillante.<\/p>\n<p>Esta es la l\u00ednea temporal en la que desarrollaron los acontecimientos de manera muy resumida:<\/p>\n<p>Primero, Sony Pictures Entertainment es hackeado por un grupo que en general se cree que estaba aliado con la Rep\u00fablica Popular Democr\u00e1tica de Corea. Luego, sin ning\u00fan orden en particular, los hackers empezaron a liberar tesoros valiosos robados, incluyendo informaci\u00f3n de pel\u00edculas, guiones de filmes que no hab\u00edan sido lanzadas, informaci\u00f3n personal de sanidad de los empleados, e emails internos, entre otra informaci\u00f3n. Finalmente, los hackers amenazaron con atacar a los cines en el lanzamiento de la pel\u00edcula de \u201cThe Interview\u201d. Los Cines Regal, una de las cadenas m\u00e1s grandes de Estados Unidos dijeron que no proyectar\u00edan la pel\u00edcula y Sony ha decidido, en un \u00faltima instancia, retrasar el lanzamiento.<\/p>\n<div class=\"pullquote\">Generalmente, cuando un grupo de hackeo patrocinado por el estado-naci\u00f3n lleva a cabo un ataque, lo hace de la manera m\u00e1s secreta posible.<\/div>\n<p>Se dice que Corea del Norte est\u00e1 detr\u00e1s de estos ataques. Debido a esto, ha habido bastante escepticismo, y con toda la raz\u00f3n. Generalmente, cuando un grupo de hackeo patrocinado por el estado-naci\u00f3n lleva a cabo un ataque, lo hace de la manera m\u00e1s secreta posible. Puedes ver una campa\u00f1a o un grupo amenazante persistente avanzado y decir que <em>probablemente<\/em> un pa\u00eds en particular ha sido el responsable del ataque. Pero, por lo general, desde el punto de vista de los atacantes, el objetivo es no es permitir la atribuci\u00f3n de la responsabilidad total de un ataque determinada. Esta meta se basa en que la atribuci\u00f3n de los ataques es una ciencia naturalmente imperfecta, en lo que a Internet se refiere.<\/p>\n<p>En este caso, el grupo que reclam\u00f3 la responsabilidad por el ataque, public\u00f3 una gr\u00e1fica llamativa y, francamente rid\u00edcula de un esqueleto en los escritorios de un buen n\u00famero de ordenadores de la red de Sony. La mayor\u00eda de los grupos de APT (amenazas persistentes avanzadas) no est\u00e1n interesados en anunciar su presencia en redes importantes. Desde entonces, el grupo de Guardians of Peace (Guardianes de Paz) ha emitido amenazas contra Sony, cin\u00e9filos y el p\u00fablico estadounidense en general.<\/p>\n<p>La pregunta sigue siendo: \u00bfCorea del Norte est\u00e1 , de alguna manera, detr\u00e1s del ataque a Sony? Threatpost y otras fuentes de noticias est\u00e1n siguiendo la pista actual del Gobierno de Estados Unidos y reportando que <a href=\"https:\/\/threatpost.com\/white-house-to-blame-sony-hack-on-north-korea\/109945\" target=\"_blank\" rel=\"noopener nofollow\">Corea del Norte realmente est\u00e1 \u201cinvolucrada\u201d en el ataque.<\/a> Los detalles de lo que el gobierno de Estados Unidos sabe, se mantienen limitados en este momento, pero supuestamente, a lo largo del d\u00eda habr\u00e1 una declaraci\u00f3n de la Casa Blanca.<\/p>\n<blockquote class=\"twitter-pullquote\"><p>Hay tanto espacio para el escepticismo como para creer que Corea del Norte es responsable del ataque a #Sony<\/p><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fkas.pr%2FkF5G&amp;text=Hay+tanto+espacio+para+el+escepticismo+como+para+creer+que+Corea+del+Norte+es+responsable+del+ataque+a+%23Sony\" class=\"btn btn-twhite\" data-lang=\"en\" data-count=\"0\" target=\"_blank\" rel=\"noopener nofollow\">Tweet<\/a><\/blockquote>\n<p>Por otro lado, la revista Wired se ha mantenido en su posici\u00f3n y contin\u00faa sugiriendo que <a href=\"http:\/\/www.wired.com\/2014\/12\/evidence-of-north-korea-hack-is-thin\/\" target=\"_blank\" rel=\"noopener nofollow\">hay poca evidencia de que haya un v\u00ednculo entre el ataque a Sony con Corea del Norte.<\/a> Wired cita tanto la dificultad de las atribuciones de los ataques, como las declaraciones de Sony y el FBI, que han afirmado p\u00fablicamente que no hay evidencia que relacione a Corea del Norte con el ataque. Es dif\u00edcil no estar de acuerdo con Wired. \u00bfPor qu\u00e9 un gobierno extranjero atacar\u00eda p\u00fablicamente a una corporaci\u00f3n extranjera por una pel\u00edcula tan absurda?<\/p>\n<p>De hecho podr\u00eda haber muchas razones.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">The Sony hack is extremely worrying. Hackers using real-world terror threats and achieving their goal is really bad for everyone<\/p>\n<p>\u2014 Eugene Kaspersky (@e_kaspersky) <a href=\"https:\/\/twitter.com\/e_kaspersky\/status\/545549242430144512?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">December 18, 2014<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br>\nAlgunos observadores creen que la furia contra la pel\u00edcula \u201cThe Interview\u201d es una excusa de Corea del Norte para demostrar la fuerza de su ciber-m\u00fasculo.<\/p>\n<p><a href=\"http:\/\/seclists.org\/dailydave\/2014\/q4\/70\" target=\"_blank\" rel=\"noopener nofollow\">El CEO de Inmunidad y antiguo cient\u00edfico de la NSA (Agencia de Seguridad Nacional) Dave Aitel ha publicado lo siguiente en el Daily Dave:<\/a> \u201cNo se trata de una pel\u00edcula, ni siquiera de Sony. Cuando se crea un programa nuclear, tienes que explotar por lo menos un misil para que otros pa\u00edses vean lo que puedes hacer. Lo mismo pasa con el mundo cibern\u00e9tico\u201d.<\/p>\n<p>Tal y como ha informado Threatpost esta ma\u00f1ana, Aitel fue uno de los primeros en publicar la teor\u00eda de que Corea del Norte podr\u00eda estar detr\u00e1s del ataque de Sony y lo compar\u00f3 con la participaci\u00f3n de Ir\u00e1n en los ataques de Shamoon que <a href=\"https:\/\/threatpost.com\/saudi-aramco-confirms-scope-malware-attack-082712\/76954\" target=\"_blank\" rel=\"noopener nofollow\">destruyeron 30.000 estaciones en la f\u00e1brica de aceite de Arabia, Saudi Aramco, en 2012.<\/a><\/p>\n<p>\u201cIran le hizo lo mismo a Saudi Aramco como una forma de demostrarle que pod\u00eda y lo har\u00eda\u201d, dijo Aitel. \u201cEs lo mismo que le ha acaba de pasar a Sony\u201d. Aunque razonables, estas explicaciones no dejan de ser meras especulaciones acerca del por qu\u00e9 o c\u00f3mo Corea del Norte podr\u00eda tener motivos para lanzar ese ataque. Sin embargo, hay tambi\u00e9n una evidencia real, forense y contextual que apunta hacia Corea del Norte.<\/p>\n<p>El investigador de Kaspersky Lab, Kurt Baumgartner se\u00f1al\u00f3 dentro de un art\u00edculo de Securelist a principios de mes, <a href=\"http:\/\/www.viruslist.com\/sp\/weblog?weblogid=208189040\" target=\"_blank\" rel=\"noopener nofollow\">una serie de similitudes entre el ataque a Sony y otros ataques generalmente atribuidos a Corea del Norte.<\/a> Baumgartner indic\u00f3 que los atacantes cubr\u00edan su rastro utilizando un malware destructivo de limpieza llamado Destover, que sobrescrib\u00eda discos duros de toda la compa\u00f1\u00eda. Seg\u00fan los informes, el mismo malware fue utilizado en los ataques de DarkSeoul contra Corea del Sur, que fueron atribuidos al pa\u00eds vecino del norte.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Just like Shamoon, Just like DarkSeoul \u2013 lot of similarities revealed by <a href=\"https:\/\/twitter.com\/k_sec?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">@k_sec<\/a> in Sony Picture hack samples analysis <a href=\"http:\/\/t.co\/DJE6hdkV72\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/DJE6hdkV72<\/a><\/p>\n<p>\u2014 codelancer (@codelancer) <a href=\"https:\/\/twitter.com\/codelancer\/status\/540597006717419520?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">December 4, 2014<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>La saga de ataques de Sony, est\u00e1 lejos de acabar ya que hay un sinf\u00edn de preguntas sin responder. Definitivamente merece la pena seguir esta historia en los pr\u00f3ximos d\u00edas, y espero que podamos aprender m\u00e1s sobre qui\u00e9n est\u00e1 detr\u00e1s de este ataque y cu\u00e1les fueron realmente sus motivaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por segunda vez en tres a\u00f1os, Sony es el protagonista de un ciberataque masivo y humillante.<\/p>\n","protected":false},"author":42,"featured_media":5086,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[1051,1050,795,51,122,22,132],"class_list":["post-5085","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news","tag-ciberataque","tag-corea-del-norte","tag-fuga-de-datos","tag-hackear","tag-hackers","tag-malware-2","tag-sony"],"hreflang":[{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/corea-del-norte-ataque-a-sony\/5085\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.es\/blog\/tag\/ciberataque\/","name":"ciberataque"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts\/5085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/comments?post=5085"}],"version-history":[{"count":3,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts\/5085\/revisions"}],"predecessor-version":[{"id":21745,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts\/5085\/revisions\/21745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/media\/5086"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/media?parent=5085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/categories?post=5085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/tags?post=5085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}