{"id":5923,"date":"2015-04-27T14:57:25","date_gmt":"2015-04-27T14:57:25","guid":{"rendered":"http:\/\/kasperskydaily.com\/spain\/?p=5923"},"modified":"2017-09-21T17:09:57","modified_gmt":"2017-09-21T15:09:57","slug":"ojos-en-el-cielo-los-drones-de-las-fuerzas-de-defensa-de-israel","status":"publish","type":"post","link":"https:\/\/www.kaspersky.es\/blog\/ojos-en-el-cielo-los-drones-de-las-fuerzas-de-defensa-de-israel\/5923\/","title":{"rendered":"Ojos en el cielo: los drones de las fuerzas de defensa de Israel"},"content":{"rendered":"<p>La seguridad de la informaci\u00f3n es el pilar y la esencia de Israel. Se le dio inter\u00e9s mucho antes de que surgiera el concepto de seguridad de la informaci\u00f3n en el siglo 21. Para un pa\u00eds de 470km de largo y 135km de ancho (como mucho), y considerando cierta hostilidad de los pa\u00edses vecinos, lo m\u00e1s importante para la seguridad nacional era saber qu\u00e9 era lo que estaba pasando a 100km alrededor de su territorio.<\/p>\n<p><a href=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2015\/04\/05220057\/1-1024x1024-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5924\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2015\/04\/05220057\/1-1024x1024-1.jpg\" alt=\"1\" width=\"1024\" height=\"1024\"><\/a>He escrito muchos art\u00edculos sobre Israel y la seguridad de la informaci\u00f3n en el campo de la tecnolog\u00eda digital, pero hoy lo analizar\u00e9 desde otro punto de vista.<\/p>\n<p>Los drones empezaron a salir en los medios de comunicaci\u00f3n durante la \u00faltima d\u00e9cada pero s las fuerzas armadas ya hab\u00edan hecho uso de ellos. Por ejemplo, en Israel el ej\u00e9rcito los usa desde 1969 y se quedaban vigilando \u00a0en el aire mientras se modificaban y actualizaban desde la tierra.<\/p>\n<p>Adem\u00e1s los drones se han convertido en uno de los art\u00edculos de exportaci\u00f3n m\u00e1s importante del pa\u00eds. Estos oficiales voladores inteligentes son enviados a muchos pa\u00edses, incluyendo Rusia. Una sola unidad cuesta entre 5 y 10 millones d\u00f3lares, se trata de contratos muy importantes.<\/p>\n<p>Hay dos tipos de drones: unos para misiones de reconocimiento y otros de ataque. . Israel es muy abierto en cuanto a los primeros, mientras que la informaci\u00f3n sobre el segundo es clasificada. Un operador de drones de Palmachin, donde se encuentra la base a\u00e9rea de Israel cerca de Rishon LeZion, nos dio informaci\u00f3n sobre el primer tipo , datos de todas formas muy interesantes.<\/p>\n<p><strong>El peque\u00f1o ayudante del ej\u00e9rcito<\/strong><\/p>\n<p>En 1960 el uso de los drones se convirti\u00f3 en el punto m\u00e1s importante de la agenda de Israel, y en 1969 se cre\u00f3 una divisi\u00f3n propia para su uso y desarrollo. Los primeros UAV (acr\u00f3nimo del ingl\u00e9s por veh\u00edculo a\u00e9reo no tripulado) eran modelos teledirigidos con una c\u00e1mara normal a bordo. El peque\u00f1o avi\u00f3n despegaba, cruzaba la frontera, hac\u00eda fotos, regresaba a la base y luego los t\u00e9cnicos se encargaban de las im\u00e1genes.<\/p>\n<p>Cuando la situaci\u00f3n en la frontera no era estable, este proceso se hac\u00eda las 24 horas del d\u00eda, y en los momentos que parec\u00eda estar todo tranquilo, los UAV despegaban solo unas cuantas veces al d\u00eda. No volaban alto y estaban susceptibles a que los derribaran, siendo reemplazados por m\u00e1s y m\u00e1s drones.<\/p>\n<div class=\"pullquote\">Como resultado de la Guerra de Yom Kipur en 1973, se tom\u00f3 la decisi\u00f3n de desarrollar la transmisi\u00f3n en vivo (streaming) desde los UAV. Esta funci\u00f3n parece ser f\u00e1cil hoy en d\u00eda, pero no lo era en los a\u00f1os 70.<\/div>\n<p>De hecho este m\u00e9todo de inteligencia no variaba mucho de la cartograf\u00eda a\u00e9rea pero s\u00ed que hab\u00eda una diferencia: si disparaban al dron, el gobierno solo perder\u00eda dinero y no personas, \u00a0el valor m\u00e1s importante de este peque\u00f1o pa\u00eds.<\/p>\n<p>Los pa\u00edses vecinos no se quedaron tranquilos. Teniendo en mente que en los 70 Israel confiaba en la recopilaci\u00f3n de datos con drones, los egipcios (no sin la ayuda de asesores de la Uni\u00f3n Sovi\u00e9tica) rotaban constantemente la disposici\u00f3n de fuerzas y los sitios de lanzamiento de misiles de la frontera.<\/p>\n<p>Como resultado, mientras el dron regresaba a la base y se procesaba la informaci\u00f3n recopilada, para entonces ya no serv\u00eda de nada. Una sorpresa muy desagradable, especialmente durante la Guerra de Yom Kipur en 1973, cuando se utiliz\u00f3 por primera vez la transmisi\u00f3n de v\u00eddeo en vivo (streaming) desde los UAV.<\/p>\n<p>Hoy en d\u00eda esto suena f\u00e1cil, pero en los 70 cuando la televisi\u00f3n y el equipo de transmisi\u00f3n solo pod\u00edan almacenarse en contenedores de carga enormes, los ingenieros ten\u00edan un gran trabajo por hacer. Israel compr\u00f3 drones americanos durante un tiempo pero, por obvias razones, Estados Unidos nunca ha tenido problemas con seguir los movimientos del enemigo en la frontera.<\/p>\n<div id=\"attachment_5925\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2015\/04\/05222952\/2.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5925\" class=\"size-large wp-image-5925\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2015\/04\/05222952\/2-1024x471.jpg\" alt=\"Primeros modelos a escala de drones americanos\" width=\"1024\" height=\"471\"><\/a><p id=\"caption-attachment-5925\" class=\"wp-caption-text\">Primeros modelos a escala de drones americanos<\/p><\/div>\n<p>Los drones producidos en EEUU al principioten\u00edan el prop\u00f3sito de provocar una respuesta de los lanzadores de misiles del enemigo para poder descubrirlos y derribarlos. Los drones americanos tampoco pod\u00edan volver a la base. Se lanzaban desde un avi\u00f3n o desde un barco hasta que volvieran a por ellos.<\/p>\n<p>Por entonces la habilidad del modelo de drones Teledyne Ryan Firebee para permanecer a flote antes de hundirse se comercializaba como una gran ventaja. Por lo tanto el uso a gran escala de este tipo de drones era demasiado caro e injustificable.<\/p>\n<p>Como resultado, en 1979 se lanz\u00f3 el primer dron producido localmente llamado IAI Scout. Este dron era tan eficaz que el ej\u00e9rcito israel\u00ed lo utiliz\u00f3 hasta el a\u00f1o 2005 y algunos estados lo siguen utilizando hoy en d\u00eda. Si lo consideramos como avi\u00f3n, es sumamente ligero (96 kilos), tiene motor de pist\u00f3n y alcanza una velocidad m\u00e1xima de 102 Km\/h.<\/p>\n<div id=\"attachment_5926\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2015\/04\/05222951\/3.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5926\" class=\"wp-image-5926 size-large\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2015\/04\/05222951\/3-1024x578.jpg\" alt=\"3\" width=\"1024\" height=\"578\"><\/a><p id=\"caption-attachment-5926\" class=\"wp-caption-text\">IAI Scout, el primer dron israel\u00ed<\/p><\/div>\n<p>Este UAV pod\u00eda permanecer 7 horas en el aire y, lo m\u00e1s importante, cargando una c\u00e1mara Tamam junto con sus lentes telesc\u00f3picos transmitiendo im\u00e1genes en directo a la base. Sus peque\u00f1as dimensiones y su habilidad para volar hasta 4km de altura lo hizo pr\u00e1cticamente invulnerable al suelo e incluso los aviones enemigos ten\u00edan problemas para derribarlo.<\/p>\n<div class=\"pullquote\">Fue entonces que se descubri\u00f3 otra ventaja de este dron: los operadores pod\u00edan cambiar de turno de manera m\u00e1s frecuente que los propios UAV.<\/div>\n<p>Por aquel entonces las im\u00e1genes transmitidas desde la c\u00e1mara eran en blanco y negro, pero luego lleg\u00f3 el color y eso consinti\u00f3 grabar tambi\u00e9n en plena oscuridad. Estos avances eran suficientes para ofrecer seguridad.<\/p>\n<p>Sin embargo, despu\u00e9s de 1973 Israel ten\u00eda menos enemigos de guerra, pero no tard\u00f3 en surgir uno nuevo. El terrorismo reemplaz\u00f3 la amenaza de guerra en gran escala y trajo consigo un nuevo desaf\u00edo: una serie de ataques constantes provenientes de todos lados.<\/p>\n<p>Los UAV ten\u00edan una nueva tarea que no era rastrear y seguir a las fuerzas armadas, sino a los veh\u00edculos aut\u00f3nomos y a las personas. La reproducci\u00f3n de v\u00eddeos en directo (streaming) dej\u00f3 de ser suficiente: los drones ten\u00edan que implementar una nueva funcionalidad de seguimiento y posici\u00f3n geogr\u00e1fica de objetos.<\/p>\n<p>Fue entonces cuando se descubri\u00f3 otra ventaja de los drones: los operadores pod\u00edan hacer cambios de turno con mayor frecuencia que los propios UAV. Si una persona tiene la tarea de supervisar un punto durante 5 horas seguidas es inevitable que su atenci\u00f3n disminuya. En el caso de los drones, un vuelo puede ser gestionado por varios equipos en diferentes turnos, con cada uno de ellos siempre alerta, teniendo as\u00ed mayor seguridad.<\/p>\n<p><strong>Explorador en el cielo<\/strong><\/p>\n<p>Es obvio que el IAI Scout no se pod\u00eda modernizar eternamente,;por lo tanto, en 1992 lleg\u00f3 una nueva generaci\u00f3n para reemplazarlo, el IAI Searcher. En 6 a\u00f1os, se cre\u00f3 otro llamado Searcher 2. \u00c9ste era m\u00e1s ancho (8,55m contra 7,22m), con mayor duraci\u00f3n de vuelo ininterrumpido (15-17 hrs contra. 12-14 hrs) y con mayor altitud de vuelo (7km contra 4,5km).<\/p>\n<div id=\"attachment_5927\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2015\/04\/05222949\/4.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5927\" class=\"wp-image-5927 size-large\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2015\/04\/05222949\/4-1024x778.jpg\" alt=\"4\" width=\"1024\" height=\"778\"><\/a><p id=\"caption-attachment-5927\" class=\"wp-caption-text\">Primera generaci\u00f3n de IAI Searcher<\/p><\/div>\n<p>Su ventaja principal era la construcci\u00f3n en m\u00f3dulo, que permit\u00eda configurar el dron de acuerdo a la tarea que deb\u00eda realizar. Adem\u00e1s de la grabaci\u00f3n de im\u00e1genes, pod\u00eda servir para coordinar las fuerzas terrestres y hacer profundos reconocimientos gracias a su m\u00f3dulo de radar de gran alcance.<\/p>\n<div id=\"attachment_5928\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2015\/04\/05222947\/5.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5928\" class=\"wp-image-5928 size-large\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/88\/2015\/04\/05222947\/5-1024x678.jpg\" alt=\"5\" width=\"1024\" height=\"678\"><\/a><p id=\"caption-attachment-5928\" class=\"wp-caption-text\">IAI Searcher 2 en el ej\u00e9rcito israel\u00ed<\/p><\/div>\n<p>Israel sigue modernizando y agregando m\u00e1s drones. Incluso antes del Searcher 2 se invent\u00f3 uno llamado IAI Heron (con una envergadura de 16,6m). Su primer vuelo fue en 1994, pero no se produjo a gran escala hasta el 2005.<\/p>\n<p>Con los tanques llenos puede volar hasta 46 horas con una altitud de 9 km. En 2012 Heron se convirti\u00f3 en el dron m\u00e1s exportado producido en Israel con un precio de hasta 10 millones de d\u00f3lares por unidad. Su sucesor, Heron TP (tambi\u00e9n conocido como Eitan) tiene una envergadura de 26 metros, m\u00e1s o menos como un Boeing 737 civil y puede llegar a 36 horas de vuelo ininterrumpido.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">IAI Heron-1, UAV developed by Israel Aerospace Industries used by 14 countries. India having the highest units (50) <a href=\"http:\/\/t.co\/S7i7TXPwV7\" target=\"_blank\" rel=\"noopener nofollow\">pic.twitter.com\/S7i7TXPwV7<\/a><\/p>\n<p>\u2014 Defence Aviation (@DefenceAviation) <a href=\"https:\/\/twitter.com\/DefenceAviation\/status\/522005451051778048?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">October 14, 2014<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Un dato importante es que todos los componentes se producen en Israel. As\u00ed no solo se crea empleo, sino tambi\u00e9n ayuda a mantener el estado \u00a0independiente de los suministros provenientes del extranjero, algo en lo que no se puede confiar al 100%.<\/p>\n<div class=\"pullquote\">Todos los componentes de los drones se producen en Israel, incluso los software.<\/div>\n<p>En la historia hubo casos en los que el uso de un arma dependi\u00f3 de la agenda de producci\u00f3n de otro pa\u00eds, que por falta de organizaci\u00f3n dej\u00f3 de enviar el producto al comprador. Los UAV de Israel se producen localmente. Y seg\u00fan algunas fuentes de informaci\u00f3n, Israel produce algunas partes de los aviones americanos.<\/p>\n<p>Los software tambi\u00e9n se producen localmente, desarrollados sobre todo por los creadores de drones. Sin embargo, algunas de sus funciones son ajustadas por el ej\u00e9rcito.<\/p>\n<p>Los drones son solo la punta del iceberg. De hecho los drones modernos tienen estaciones operativas que tambi\u00e9n se venden por grandes cantidades de dinero.<\/p>\n<p>Se analizan los datos obtenidos por un dron y luego deber\u00edan almacenarse, y es entonces cuando estas soluciones entran en juego (curiosamente, la informaci\u00f3n obtenida por la mayor\u00eda de drones se graba en\u2026 DVDs ya que es lo m\u00e1s barato y confiable para almacenar).<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"lt\" dir=\"ltr\"><a href=\"http:\/\/t.co\/cHMLWHE9PW\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/cHMLWHE9PW<\/a> Technology \u2013 IAI HERON UAV Drones <a href=\"http:\/\/t.co\/L8D3PeHz8C\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/L8D3PeHz8C<\/a><\/p>\n<p>\u2014 Unofficial \u2721MOSSAD\u2721 (@MossadNews) <a href=\"https:\/\/twitter.com\/MossadNews\/status\/516950835532947459?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">September 30, 2014<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>Guerra y Paz<\/strong><\/p>\n<p>Los drones eran muy \u00fatiles durante la guerra cl\u00e1sica, con extensas tropas armadas y una l\u00ednea de batalla distinta. Hoy en d\u00eda, los conflictos surgen generalmente en zonas muy pobladas donde hay mucha gente (relativamente) pac\u00edfica y por eso los drones se han convertido en una herramienta de seguridad de la informaci\u00f3n.<\/p>\n<blockquote class=\"twitter-pullquote\"><p>La historia de c\u00f3mo los UAV de Israel defienden al pa\u00eds desde la tierra, el cielo y dentro del campo de la informaci\u00f3n<\/p><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fkas.pr%2FyG2B&amp;text=La+historia+de+c%C3%B3mo+los+UAV+de+Israel+defienden+al+pa%C3%ADs+desde+la+tierra%2C+el+cielo+y+dentro+del+campo+de+la+informaci%C3%B3n\" class=\"btn btn-twhite\" data-lang=\"en\" data-count=\"0\" target=\"_blank\" rel=\"noopener nofollow\">Tweet<\/a><\/blockquote>\n<p>Llegar\u00e1 el d\u00eda en que exmilitares est\u00e9n jubilados y creen su propio negocio basado en la experiencia adquirida durante su estancia en el ej\u00e9rcito. Considerando el inter\u00e9s en los drones, los desarrolladores israelitas tienen un mundo de oportunidades. Adem\u00e1s de ser un entretenimiento, los drones podr\u00edan ser el sustituto de las gr\u00faas en el sector de la construcci\u00f3n.<\/p>\n<p>Los drones podr\u00edan ser buenos mensajeros y ser\u00eda un gusto para los que viven frustrados con los mensajeros de carne y hueso. Como dice un personaje del libro \u201cPuerta al Verano\u201d de Robert Heinlein, \u201cEso es lo que tienen de bueno los trastos ultra secretos; que no los patentan\u201d. Es interesante ver c\u00f3mo algunas tecnolog\u00edas desarrolladas principalmente para proteger a los seres humanos, se pueden utilizar tambi\u00e9n para facilitar la vida cotidiana.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00f3mo los UAV de Israel defienden al pa\u00eds desde la tierra, el cielo y dentro del campo de la informaci\u00f3n.<\/p>\n","protected":false},"author":609,"featured_media":5924,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1348,6],"tags":[613,1227,1226,61,1055],"class_list":["post-5923","post","type-post","status-publish","format-standard","has-post-thumbnail","category-threats","category-news","tag-drones","tag-iai","tag-israel","tag-seguridad","tag-uav"],"hreflang":[{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/ojos-en-el-cielo-los-drones-de-las-fuerzas-de-defensa-de-israel\/5923\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.es\/blog\/tag\/drones\/","name":"drones"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts\/5923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/comments?post=5923"}],"version-history":[{"count":1,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts\/5923\/revisions"}],"predecessor-version":[{"id":11421,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/posts\/5923\/revisions\/11421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/media\/5924"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/media?parent=5923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/categories?post=5923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.es\/blog\/wp-json\/wp\/v2\/tags?post=5923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}